{"id":2681,"count":1,"description":"","link":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/","name":"The Fallen","slug":"the-fallen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Fallen Archives - d20 Radio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Fallen Archives - d20 Radio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/\" \/>\n<meta property=\"og:site_name\" content=\"d20 Radio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/tag\\\/the-fallen\\\/\",\"url\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/tag\\\/the-fallen\\\/\",\"name\":\"The Fallen Archives - d20 Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/tag\\\/the-fallen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/tag\\\/the-fallen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Fallen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#website\",\"url\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/\",\"name\":\"d20 Radio\",\"description\":\"Where Gamers Roll\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#organization\",\"name\":\"d20 Radio\",\"url\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cropped-gamernation_logo_siteheader-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/cropped-gamernation_logo_siteheader-2.jpg\",\"width\":300,\"height\":100,\"caption\":\"d20 Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.d20radio.com\\\/main\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Fallen Archives - d20 Radio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/","og_locale":"en_US","og_type":"article","og_title":"The Fallen Archives - d20 Radio","og_url":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/","og_site_name":"d20 Radio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/","url":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/","name":"The Fallen Archives - d20 Radio","isPartOf":{"@id":"https:\/\/www.d20radio.com\/main\/#website"},"breadcrumb":{"@id":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.d20radio.com\/main\/tag\/the-fallen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.d20radio.com\/main\/"},{"@type":"ListItem","position":2,"name":"The Fallen"}]},{"@type":"WebSite","@id":"https:\/\/www.d20radio.com\/main\/#website","url":"https:\/\/www.d20radio.com\/main\/","name":"d20 Radio","description":"Where Gamers Roll","publisher":{"@id":"https:\/\/www.d20radio.com\/main\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.d20radio.com\/main\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.d20radio.com\/main\/#organization","name":"d20 Radio","url":"https:\/\/www.d20radio.com\/main\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.d20radio.com\/main\/#\/schema\/logo\/image\/","url":"https:\/\/www.d20radio.com\/main\/wp-content\/uploads\/2015\/03\/cropped-gamernation_logo_siteheader-2.jpg","contentUrl":"https:\/\/www.d20radio.com\/main\/wp-content\/uploads\/2015\/03\/cropped-gamernation_logo_siteheader-2.jpg","width":300,"height":100,"caption":"d20 Radio"},"image":{"@id":"https:\/\/www.d20radio.com\/main\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.d20radio.com\/main\/wp-json\/wp\/v2\/tags\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.d20radio.com\/main\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.d20radio.com\/main\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.d20radio.com\/main\/wp-json\/wp\/v2\/posts?tags=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}